{"id":16,"date":"2026-01-19T14:40:09","date_gmt":"2026-01-19T17:40:09","guid":{"rendered":"https:\/\/sbm.org.br\/brics\/?page_id=16"},"modified":"2026-08-15T22:10:06","modified_gmt":"2026-08-16T01:10:06","slug":"home-brics","status":"publish","type":"page","link":"https:\/\/sbm.org.br\/brics\/","title":{"rendered":"Home BRICS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16\" class=\"elementor elementor-16\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ea6a20 e-flex e-con-boxed jltma-glass-effect-no e-con e-parent\" data-id=\"8ea6a20\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6de055a jltma-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"6de055a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7badcfb e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"7badcfb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e3c7e82 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"e3c7e82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/sbm.org.br\/brics\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1440\" height=\"672\" src=\"https:\/\/sbm.org.br\/brics\/wp-content\/uploads\/sites\/43\/2026\/02\/Logo-7th-BRICS-CONFERENCE-2.png\" class=\"attachment-full size-full wp-image-178\" alt=\"\" srcset=\"https:\/\/sbm.org.br\/brics\/wp-content\/uploads\/sites\/43\/2026\/02\/Logo-7th-BRICS-CONFERENCE-2.png 1440w, https:\/\/sbm.org.br\/brics\/wp-content\/uploads\/sites\/43\/2026\/02\/Logo-7th-BRICS-CONFERENCE-2-300x140.png 300w, https:\/\/sbm.org.br\/brics\/wp-content\/uploads\/sites\/43\/2026\/02\/Logo-7th-BRICS-CONFERENCE-2-1024x478.png 1024w, https:\/\/sbm.org.br\/brics\/wp-content\/uploads\/sites\/43\/2026\/02\/Logo-7th-BRICS-CONFERENCE-2-768x358.png 768w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41cd381 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"41cd381\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">S\u00e3o Paulo, Brazil<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8999711 elementor-widget-divider--view-line jltma-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"8999711\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a70989b jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"a70989b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">August 18-21, 2026<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e1fef2 jltma-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"3e1fef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e434641 e-flex e-con-boxed jltma-glass-effect-no e-con e-parent\" data-id=\"e434641\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68b9f72 elementor-widget-divider--view-line jltma-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"68b9f72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73222fe jltma-glass-effect-no elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"73222fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\"\n\t\t\tdata-hamburger-icon=\"\"\n\t\t\tdata-hamburger-icon-type=\"icon\"\n\t\t\tdata-responsive-breakpoint=\"1024\"\n\t\t\tdata-close-on-anchor=\"no\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\"  type=\"button\" aria-label=\"hamburger-icon\">\n                                    <span class=\"elementskit-menu-hamburger-icon\"><\/span><span class=\"elementskit-menu-hamburger-icon\"><\/span><span class=\"elementskit-menu-hamburger-icon\"><\/span>\n                            <\/button>\n            <div id=\"ekit-megamenu-primary-menu\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page-no ekit-nav-dropdown-hover\"><ul id=\"menu-primary-menu\" class=\"elementskit-navbar-nav elementskit-menu-po-center submenu-click-on-icon\"><li id=\"menu-item-18\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-home menu-item-18 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/sbm.org.br\/brics\/\" class=\"ekit-menu-nav-link\">Home<\/a><\/li>\n<li id=\"menu-item-19\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-19 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"#a\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">About<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-218\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-218 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/sbm.org.br\/brics\/about-event\/\" class=\" dropdown-item\">About the event<\/a>\t<li id=\"menu-item-111\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-111 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/sbm.org.br\/brics\/committee\/\" class=\" dropdown-item\">Committee<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-291\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-291 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/sbm.org.br\/brics\/submission\/\" class=\"ekit-menu-nav-link\">Submission<\/a><\/li>\n<li id=\"menu-item-292\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-292 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"#a\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Program<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-217\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-217 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/sbm.org.br\/brics\/program\/\" class=\" dropdown-item\">Program<\/a>\t<li id=\"menu-item-492\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-492 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/sbm.org.br\/brics\/thematic-sessions\/\" class=\" dropdown-item\">Thematic Sessions<\/a>\t<li id=\"menu-item-229\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-229 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/sbm.org.br\/brics\/plenary-speakers\/\" class=\" dropdown-item\">Plenary Speakers<\/a>\t<li id=\"menu-item-375\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-375 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/sbm.org.br\/brics\/distinguished-speaker\/\" class=\" dropdown-item\">Distinguished Lectures<\/a>\t<li id=\"menu-item-742\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-742 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/sbm.org.br\/brics\/poster-sessions\/\" class=\" dropdown-item\">Poster Sessions<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-543\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-543 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/sbm.org.br\/brics\/accommodation\/\" class=\"ekit-menu-nav-link\">Accommodation<\/a><\/li>\n<li id=\"menu-item-23\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-23 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/eventos.sbm.org.br\/\" class=\"ekit-menu-nav-link\">Registration<\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ccb6dc elementor-widget-divider--view-line jltma-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"3ccb6dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29955db e-flex e-con-boxed jltma-glass-effect-no e-con e-parent\" data-id=\"29955db\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d9a345 jltma-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"0d9a345\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab6047e jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"ab6047e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">About the event<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8eb0189 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"8eb0189\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">7th BRICS Mathematics Conference - Brazil<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8de83a4 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"8de83a4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8134aa jltma-glass-effect-no elementor-widget elementor-widget-video\" data-id=\"d8134aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=OORULv_w6m0&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28a4ac8 elementor-widget__width-initial elementor-widget-mobile__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"28a4ac8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">The <\/span><b>BRICS Mathematics Conference<\/b><span style=\"font-weight: 400\"> is a premier international scientific forum that unites the mathematical communities of Brazil, Russia, India, China, and South Africa. As a vital institutional space for dialogue, the conference fosters scientific cooperation, strengthens academic ties, and builds joint initiatives across the BRICS nations&#8217; leading universities and research centers.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ff237d e-flex e-con-boxed jltma-glass-effect-no e-con e-parent\" data-id=\"9ff237d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c252fbf jltma-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"c252fbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b0611f4 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"b0611f4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4b79011 e-con-full e-flex jltma-glass-effect-no e-con e-child\" data-id=\"4b79011\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d0759e elementor-widget__width-inherit jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"3d0759e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Event Venue<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43fc9cd elementor-align-start elementor-widget__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width jltma-glass-effect-no elementor-widget elementor-widget-icon-list\" data-id=\"43fc9cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-location-arrow\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M444.52 3.52L28.74 195.42c-47.97 22.39-31.98 92.75 19.19 92.75h175.91v175.91c0 51.17 70.36 67.17 92.75 19.19l191.9-415.78c15.99-38.39-25.59-79.97-63.97-63.97z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong><em>Thematic Sessions:<\/em><\/strong><Br><strong>IME-USP  Bloco A \u2014 Instituto de Matem\u00e1tica, Estat\u00edstica e Ci\u00eancia da Computa\u00e7\u00e3o<\/strong><br \/> Rua do Mat\u00e3o, 1010, Cidade Universit\u00e1ria, S\u00e3o Paulo \u2013 SP <br \/> <a href=\"https:\/\/www.ime.usp.br\/localizacao\/\" target=\"blank\">https:\/\/www.ime.usp.br\/localizacao\/<\/a><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-location-arrow\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M444.52 3.52L28.74 195.42c-47.97 22.39-31.98 92.75 19.19 92.75h175.91v175.91c0 51.17 70.36 67.17 92.75 19.19l191.9-415.78c15.99-38.39-25.59-79.97-63.97-63.97z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong><em>Plenary, invited, contributed talks, and coffee breaks:<\/em><\/strong><Br><strong>FAU-USP \u2014 Faculdade de Arquitetura e Urbanismo e de Design<\/strong><br \/> Rua do Lago, 876, Cidade Universit\u00e1ria, S\u00e3o Paulo \u2013 SP<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-location-arrow\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M444.52 3.52L28.74 195.42c-47.97 22.39-31.98 92.75 19.19 92.75h175.91v175.91c0 51.17 70.36 67.17 92.75 19.19l191.9-415.78c15.99-38.39-25.59-79.97-63.97-63.97z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong><em>Opening ceremony:<\/em><\/strong><Br><strong>BBM \u2014 Biblioteca Brasiliana Guita e Jos\u00e9 Mindlin \/ Audit\u00f3rio Istv\u00e1n Jancs\u00f3<\/strong><br \/> Rua da Biblioteca, 21, Espa\u00e7o Brasiliana, Cidade Universit\u00e1ria, S\u00e3o Paulo \u2013 SP<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c18ab2 jltma-glass-effect-no elementor-widget elementor-widget-google_maps\" data-id=\"5c18ab2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Universidade%20de%20S%C3%A3o%20Paulo&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Universidade de S\u00e3o Paulo\"\n\t\t\t\t\taria-label=\"Universidade de S\u00e3o Paulo\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>S\u00e3o Paulo, Brazil August 18-21, 2026 Home About About the event Committee Submission Program Program Thematic Sessions Plenary Speakers Distinguished Lectures Accommodation Registration X About the event 7th BRICS Mathematics Conference &#8211; Brazil https:\/\/www.youtube.com\/watch?v=OORULv_w6m0 The BRICS Mathematics Conference is a premier international scientific forum that unites the mathematical communities of Brazil, Russia, India, China, and [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-16","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sbm.org.br\/brics\/wp-json\/wp\/v2\/pages\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbm.org.br\/brics\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sbm.org.br\/brics\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sbm.org.br\/brics\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sbm.org.br\/brics\/wp-json\/wp\/v2\/comments?post=16"}],"version-history":[{"count":64,"href":"https:\/\/sbm.org.br\/brics\/wp-json\/wp\/v2\/pages\/16\/revisions"}],"predecessor-version":[{"id":694,"href":"https:\/\/sbm.org.br\/brics\/wp-json\/wp\/v2\/pages\/16\/revisions\/694"}],"wp:attachment":[{"href":"https:\/\/sbm.org.br\/brics\/wp-json\/wp\/v2\/media?parent=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}